{"id":1293,"date":"2025-10-14T05:58:42","date_gmt":"2025-10-14T05:58:42","guid":{"rendered":"https:\/\/hpacificcapital.com\/?page_id=1293"},"modified":"2026-05-05T22:32:52","modified_gmt":"2026-05-05T22:32:52","slug":"sobre-nosotros","status":"publish","type":"page","link":"https:\/\/hpacificcapital.com\/pt\/sobre-nosotros\/","title":{"rendered":"Sobre N\u00f3s"},"content":{"rendered":"<section class=\"section\" id=\"section_765328440\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0px;margin-bottom:0px;max-width:100%;height:50px;background-color:rgba(0, 0, 0, 0);\"><\/div>\n\n<div class=\"row row-collapse align-equal\"  id=\"row-379316525\">\n\n\n\t<div id=\"col-1789454255\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-2022107368\" class=\"text title-sans-regular\">\n\t\t\n\n<h1>A firma<\/h1>\n\t\t\n<style>\n#text-2022107368 {\n  font-size: 2.5rem;\n  line-height: 1.1;\n  color: rgb(0,0,0);\n}\n#text-2022107368 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_986274675\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"558\" src=\"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Mapa-1400x766.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Mapa-1400x766.png 1400w, https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Mapa-600x328.png 600w, https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Mapa-731x400.png 731w, https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Mapa-768x420.png 768w, https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Mapa.png 1526w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_986274675 {\n  width: 85%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1789454255 > .col-inner {\n  padding: 10% 6% 0px 6%;\n}\n@media (min-width:550px) {\n  #col-1789454255 > .col-inner {\n    padding: 5% 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1064868126\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-2301001500\" class=\"text\">\n\t\t\n\n<p>A Pacific Capital se consolidou como uma firma de alcance global, especializada em banco de investimento e gest\u00e3o de capital, com uma abordagem estruturada e presen\u00e7a ativa na regi\u00e3o da Am\u00e9rica Latina (LATAM).<\/p>\n<p>Nossa equipe \u00e9 composta por profissionais com ampla experi\u00eancia em banco, finan\u00e7as corporativas e gest\u00e3o estrat\u00e9gica, apoiados por uma rede s\u00f3lida de parceiros institucionais e grupos de interesse que abrangem os principais mercados e setores onde atuamos.<\/p>\n<p>Focamo-nos em estruturar solu\u00e7\u00f5es financeiras e de capital que impulsionem o crescimento sustent\u00e1vel de nossos clientes e parceiros. Participamos ativamente de processos de fus\u00f5es e aquisi\u00e7\u00f5es (M&amp;A), capta\u00e7\u00e3o de capital e financiamento estruturado.<\/p>\n<p>Ao longo de nossa trajet\u00f3ria, estruturamos mais de USD 5 bilh\u00f5es em valor transacional para mais de uma centena de clientes que operam em diversos setores e ind\u00fastrias voltados para a Am\u00e9rica Latina.<\/p>\n<p>Hoje, continuamos ampliando nosso alcance global, com opera\u00e7\u00f5es e relacionamentos estrat\u00e9gicos nos Estados Unidos, Europa e \u00c1sia, consolidando nossa posi\u00e7\u00e3o como uma plataforma de investimento que transforma capital em impacto sustent\u00e1vel.<\/p>\n\t\t\n<style>\n#text-2301001500 {\n  font-size: 1.1rem;\n  color: rgb(0,0,0);\n}\n#text-2301001500 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1064868126 > .col-inner {\n  padding: 5% 6% 6% 6%;\n}\n@media (min-width:550px) {\n  #col-1064868126 > .col-inner {\n    padding: 7% 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<\/div>\n\n\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0px;margin-bottom:0px;max-width:100%;height:50px;background-color:rgba(0, 0, 0, 0);\"><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_765328440 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":586,"parent":0,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"footnotes":""},"class_list":["post-1293","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sobre Nosotros | Pacific Capital | La Firma de Inversi\u00f3n en LATAM<\/title>\n<meta name=\"description\" content=\"En Pacific Capital somos el puente entre el capital privado y el crecimiento empresarial de LATAM, estructurando empresas, apoyando en M&amp;A y acompa\u00f1ando el desarrollo en la regi\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hpacificcapital.com\/pt\/sobre-nosotros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre Nosotros | Pacific Capital | La Firma de Inversi\u00f3n en LATAM\" \/>\n<meta property=\"og:description\" content=\"En Pacific Capital somos el puente entre el capital privado y el crecimiento empresarial de LATAM, estructurando empresas, apoyando en M&amp;A y acompa\u00f1ando el desarrollo en la regi\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hpacificcapital.com\/pt\/sobre-nosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"Pacific Capital\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T22:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Logo-ES-Negro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"742\" \/>\n\t<meta property=\"og:image:height\" content=\"182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"38 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/\",\"url\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/\",\"name\":\"Sobre Nosotros | Pacific Capital | La Firma de Inversi\u00f3n en LATAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hpacificcapital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-ES-Negro.png\",\"datePublished\":\"2025-10-14T05:58:42+00:00\",\"dateModified\":\"2026-05-05T22:32:52+00:00\",\"description\":\"En Pacific Capital somos el puente entre el capital privado y el crecimiento empresarial de LATAM, estructurando empresas, apoyando en M&A y acompa\u00f1ando el desarrollo en la regi\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hpacificcapital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-ES-Negro.png\",\"contentUrl\":\"https:\\\/\\\/hpacificcapital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-ES-Negro.png\",\"width\":742,\"height\":182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/sobre-nosotros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hpacificcapital.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre Nosotros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hpacificcapital.com\\\/#website\",\"url\":\"https:\\\/\\\/hpacificcapital.com\\\/\",\"name\":\"Pacific Capital\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hpacificcapital.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre Nosotros | Pacific Capital | La Firma de Inversi\u00f3n en LATAM","description":"En Pacific Capital somos el puente entre el capital privado y el crecimiento empresarial de LATAM, estructurando empresas, apoyando en M&A y acompa\u00f1ando el desarrollo en la regi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hpacificcapital.com\/pt\/sobre-nosotros\/","og_locale":"pt_BR","og_type":"article","og_title":"Sobre Nosotros | Pacific Capital | La Firma de Inversi\u00f3n en LATAM","og_description":"En Pacific Capital somos el puente entre el capital privado y el crecimiento empresarial de LATAM, estructurando empresas, apoyando en M&A y acompa\u00f1ando el desarrollo en la regi\u00f3n","og_url":"https:\/\/hpacificcapital.com\/pt\/sobre-nosotros\/","og_site_name":"Pacific Capital","article_modified_time":"2026-05-05T22:32:52+00:00","og_image":[{"width":742,"height":182,"url":"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Logo-ES-Negro.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"38 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hpacificcapital.com\/sobre-nosotros\/","url":"https:\/\/hpacificcapital.com\/sobre-nosotros\/","name":"Sobre Nosotros | Pacific Capital | La Firma de Inversi\u00f3n en LATAM","isPartOf":{"@id":"https:\/\/hpacificcapital.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hpacificcapital.com\/sobre-nosotros\/#primaryimage"},"image":{"@id":"https:\/\/hpacificcapital.com\/sobre-nosotros\/#primaryimage"},"thumbnailUrl":"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Logo-ES-Negro.png","datePublished":"2025-10-14T05:58:42+00:00","dateModified":"2026-05-05T22:32:52+00:00","description":"En Pacific Capital somos el puente entre el capital privado y el crecimiento empresarial de LATAM, estructurando empresas, apoyando en M&A y acompa\u00f1ando el desarrollo en la regi\u00f3n","breadcrumb":{"@id":"https:\/\/hpacificcapital.com\/sobre-nosotros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hpacificcapital.com\/sobre-nosotros\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/hpacificcapital.com\/sobre-nosotros\/#primaryimage","url":"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Logo-ES-Negro.png","contentUrl":"https:\/\/hpacificcapital.com\/wp-content\/uploads\/2025\/07\/Logo-ES-Negro.png","width":742,"height":182},{"@type":"BreadcrumbList","@id":"https:\/\/hpacificcapital.com\/sobre-nosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hpacificcapital.com\/"},{"@type":"ListItem","position":2,"name":"Sobre Nosotros"}]},{"@type":"WebSite","@id":"https:\/\/hpacificcapital.com\/#website","url":"https:\/\/hpacificcapital.com\/","name":"Pacific Capital","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hpacificcapital.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/pages\/1293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/comments?post=1293"}],"version-history":[{"count":11,"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/pages\/1293\/revisions"}],"predecessor-version":[{"id":1796,"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/pages\/1293\/revisions\/1796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/media\/586"}],"wp:attachment":[{"href":"https:\/\/hpacificcapital.com\/pt\/wp-json\/wp\/v2\/media?parent=1293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}